{"id":2147,"date":"2021-02-19T18:00:18","date_gmt":"2021-02-19T17:00:18","guid":{"rendered":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/?p=2147"},"modified":"2021-02-19T18:00:18","modified_gmt":"2021-02-19T17:00:18","slug":"lieux-de-culture-fermes-culturebox-ouverte","status":"publish","type":"post","link":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/2021\/02\/19\/lieux-de-culture-fermes-culturebox-ouverte\/","title":{"rendered":"Lieux de culture ferm\u00e9s, Culturebox ouverte !"},"content":{"rendered":"\n<p style=\"text-align:left\"><em>Le 1<\/em><sup><em>er<\/em><\/sup><em> f\u00e9vrier 2021 marque les d\u00e9buts d\u2019une nouvelle \u00e9mission t\u00e9l\u00e9visuelle sur le canal 19 de la TNT (France \u00d4)&nbsp;: Culturebox. Dans un contexte de pand\u00e9mie mondiale qui s\u2019accompagne de la fermeture des lieux de cultures, France T\u00e9l\u00e9visions a d\u00e9cid\u00e9 de remettre du baume au c\u0153ur aux amateurs de th\u00e9\u00e2tre, de spectacles et d&rsquo;expositions en diffusant en continu des \u00e9missions culturelles afin de \u00ab&nbsp;soutenir la culture&nbsp;\u00bb.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"159\" src=\"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-content\/uploads\/sites\/3\/2021\/02\/culturebox.png\" alt=\"\" class=\"wp-image-2148\" \/><figcaption>Nouveau logo de l&rsquo;\u00e9mission (\u00a9 France T\u00e9l\u00e9visions)<\/figcaption><\/figure><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Bienvenue sur culturebox, la cha\u00eene \u00e9ph\u00e9m\u00e8re 100% d\u00e9di\u00e9e \u00e0 la culture, au spectacle vivant et aux artistes.<\/p><cite>France T\u00e9l\u00e9visions<\/cite><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">Apr\u00e8s l&rsquo;aide \u00e0 l&rsquo;\u00e9ducation, l&rsquo;aide \u00e0 la culture<\/h4>\n\n\n\n<p>Ayant d\u00e9j\u00e0 diffus\u00e9 des programmes scolaires pendant les confinements pr\u00e9c\u00e9dents, France T\u00e9l\u00e9visions propose d\u00e9sormais son aide \u00e0 un domaine qui en fortement besoin \u00e9galement : la culture. Ferm\u00e9s depuis de nombreux mois, les mus\u00e9es, les op\u00e9ras, les salles de concerts et les salles de spectacles prennent la poussi\u00e8re et le public s&rsquo;impatiente.<\/p>\n\n\n\n<p>C&rsquo;est dans cette perspective que France T\u00e9l\u00e9vision, notamment par le soutien du minist\u00e8re de la Culture et le conseil sup\u00e9rieur de l&rsquo;audiovisuel (CSA), a ouvert ce lundi 1er f\u00e9vrier 2021 la nouvelle cha\u00eene \u00ab\u00a0Culturebox\u00a0\u00bb. Emission culturelle, cette chaine propose au public des spectacles et des visites culturelles tout en laissant la parole aux professionnels de la culture et aux artistes.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Apr\u00e8s notre mobilisation au printemps dernier pour assurer la continuit\u00e9 p\u00e9dagogique dans le contexte du confinement, France T\u00e9l\u00e9visions se devait d&rsquo;\u00eatre aujourd&rsquo;hui aux c\u00f4t\u00e9s du monde de la culture particuli\u00e8rement affect\u00e9 par la crise sanitaire.\u00a0\u00bb<\/p><cite>Delphine Ernotte Cunci, Pr\u00e9sidente de France T\u00e9l\u00e9visions<\/cite><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">Une cha\u00eene \u00e9ph\u00e9m\u00e8re, vari\u00e9e et continue<\/h4>\n\n\n\n<p>Cette cha\u00eene culturelle diffusera des programmes en continu (24h\/24) jusqu&rsquo;\u00e0 ce que les lieux de culture rouvrent. Disponible gratuitement et diffus\u00e9e \u00e9galement en direct sur le site internet de France T\u00e9l\u00e9vision, cette \u00e9mission a \u00e9t\u00e9 inaugur\u00e9e par dans la soir\u00e9e du lundi 1er f\u00e9vrier lors d&rsquo;une soir\u00e9e anim\u00e9e par Daphn\u00e9 B\u00fcrki et Rapha\u00ebl Yem.<\/p>\n\n\n\n<p>L&rsquo;occasion de d\u00e9couvrir ou de red\u00e9couvrir des \u00e9missions et des concerts en tout genre pour tout amateur de culture musicale ou artistique !<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"381\" src=\"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-content\/uploads\/sites\/3\/2021\/02\/cultu.png\" alt=\"\" class=\"wp-image-2151\" srcset=\"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-content\/uploads\/sites\/3\/2021\/02\/cultu.png 605w, https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-content\/uploads\/sites\/3\/2021\/02\/cultu-300x189.png 300w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><figcaption>Mercredi 3 f\u00e9vrier, dans la matin\u00e9e : un reportage sur les com\u00e9dies musicales (\u00a9 France T\u00e9l\u00e9visions) <\/figcaption><\/figure><\/div>\n\n\n\n<p>Diffusion en direct (ou sur le canal 19 de la TNT) : <a href=\"https:\/\/www.france.tv\/spectacles-et-culture\/2261129-culturebox-en-direct.html\">https:\/\/www.france.tv\/spectacles-et-culture\/2261129-culturebox-en-direct.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 1er f\u00e9vrier 2021 marque les d\u00e9buts d\u2019une nouvelle \u00e9mission t\u00e9l\u00e9visuelle sur le canal 19 de la TNT (France \u00d4)&nbsp;:<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[24,7],"tags":[],"class_list":["post-2147","post","type-post","status-publish","format-standard","hentry","category-action-culturelle","category-site-web-culturel"],"_links":{"self":[{"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/posts\/2147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/comments?post=2147"}],"version-history":[{"count":5,"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/posts\/2147\/revisions"}],"predecessor-version":[{"id":2550,"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/posts\/2147\/revisions\/2550"}],"wp:attachment":[{"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/media?parent=2147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/categories?post=2147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larevuedespectateurs.artecom.studio\/20201\/wp-json\/wp\/v2\/tags?post=2147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}